{"id":10596,"date":"2021-05-05T12:15:45","date_gmt":"2021-05-05T11:15:45","guid":{"rendered":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/"},"modified":"2021-05-05T12:15:45","modified_gmt":"2021-05-05T11:15:45","slug":"jap","status":"publish","type":"post","link":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/","title":{"rendered":"Jornadas de Acompa\u00f1amiento Profesional"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb3.22&#8243;][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb3.25&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.4.7&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243;]<\/p>\n<p>La Federaci\u00f3n de Antiguos Alumnos y Antiguas Alumnas de Don Bosco de nuestra zona ha desarrollado el proyecto JAP: Jornadas de Acompa\u00f1amiento Profesional.\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAutor (Texto)\u00bb _builder_version=\u00bb4.4.7&#8243; text_font=\u00bb||on||\u00bb hover_enabled=\u00bb0&#8243;]<\/p>\n<p>Por Rita Soriano<\/p>\n<p>[\/et_pb_text][et_pb_image align_tablet=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.4.7&#8243; hover_enabled=\u00bb0&#8243; always_center_on_mobile=\u00bbon\u00bb title_text=\u00bbjap\u00bb src=\u00bbhttps:\/\/monzon.salesianos.edu\/wp-content\/uploads\/2021\/05\/jap.png\u00bb][\/et_pb_image][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.4.7&#8243; text_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243;]<\/p>\n<div>Con el programa JAP la Asociaci\u00f3n de Antiguos Alumnos pretende cubrir uno de los objetivos: proteger y acompa\u00f1ar al alumnado. Han sido tres jornadas (en s\u00e1bado) en las que los antiguos alumnos pueden dar su testimonio profesional que servir\u00e1 de orientaci\u00f3n acad\u00e9mica y profesional para los estudiantes. El formato ha consistido en un primer momento de testimonio para cada orador, seguido de una mesa redonda para preguntas abiertas. Todo ello en formato online y transmitiendo desde las instalaciones de la EUSS (Escuela Universitaria Salesiana de Sarri\u00e0).<\/div>\n<div>\u00a0<\/div>\n<div>Cada s\u00e1bado se ha convocado un \u00e1mbito distinto: Cient\u00edfico-T\u00e9cnico, Cient\u00edfico-Sanitario y Social-Human\u00edstico. En estos encuentros se\u00a0han\u00a0dado cita antiguos alumnos de diferentes ramas del conocimiento que no s\u00f3lo han aportado su experiencia actual desde el punto de vista laboral, sino que han mostrado todo un recorrido acad\u00e9mico y vital que les ha permitido llegar hasta donde est\u00e1n. Han transmitido, entre otros aspectos, la importancia de la apertura de mente, de los idiomas, del coraje, de vencer el miedo a equivocarse as\u00ed como el valor de la pasi\u00f3n como motor de la formaci\u00f3n continuada, que se hace imprescindible en toda carrera profesional,\u00a0sea del \u00e1mbito que sea.<\/div>\n<div><span style=\"font-family: Lucida Grande, Lucida Sans, Arial, sans-serif;\">Desde Salesianos de Monz\u00f3n hemos podido aportar el testimonio de dos de nuestros antiguos alumnos: Sof\u00eda Peruga (M\u00e9dica residente de cirug\u00eda ortop\u00e9dica y traumatolog\u00eda) y Noel Citoler\u00a0<\/span>\u00a0(Ge\u00f3grafo y actualmente T\u00e9cnico de tramitaci\u00f3n y medio ambiente). Han sido tres jornadas de sumo inter\u00e9s con el aliciente de ver, como conferenciantes, a dos de nuestros antiguos alumnos.\u00a0\u00a0<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Federaci\u00f3n de Antiguos Alumnos y Antiguas Alumnas de Don Bosco de nuestra zona ha desarrollado el proyecto JAP: Jornadas de Acompa\u00f1amiento Profesional.\u00a0 Por Rita Soriano Con el programa JAP la Asociaci\u00f3n de Antiguos Alumnos pretende cubrir uno de los objetivos: proteger y acompa\u00f1ar al alumnado. Han sido tres jornadas (en s\u00e1bado) en las que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[28,15,10,25],"tags":[],"class_list":["post-10596","post","type-post","status-publish","format-standard","hentry","category-antiguos-alumnos","category-bachillerato","category-colegio","category-familia-salesiana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jornadas de Acompa\u00f1amiento Profesional - Colegio Santo Domingo Savio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/monzon.salesianos.edu\/colegio\/jap\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornadas de Acompa\u00f1amiento Profesional - Colegio Santo Domingo Savio\" \/>\n<meta property=\"og:description\" content=\"La Federaci\u00f3n de Antiguos Alumnos y Antiguas Alumnas de Don Bosco de nuestra zona ha desarrollado el proyecto JAP: Jornadas de Acompa\u00f1amiento Profesional.\u00a0 Por Rita Soriano Con el programa JAP la Asociaci\u00f3n de Antiguos Alumnos pretende cubrir uno de los objetivos: proteger y acompa\u00f1ar al alumnado. Han sido tres jornadas (en s\u00e1bado) en las que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/monzon.salesianos.edu\/colegio\/jap\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Santo Domingo Savio\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-05T11:15:45+00:00\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dfdb4afc92a954e307946b4c7b72b0f4\"},\"headline\":\"Jornadas de Acompa\u00f1amiento Profesional\",\"datePublished\":\"2021-05-05T11:15:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/\"},\"wordCount\":448,\"commentCount\":0,\"articleSection\":[\"Antiguos Alumnos\",\"Bachillerato\",\"Colegio\",\"Familia Salesiana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/\",\"url\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/\",\"name\":\"Jornadas de Acompa\u00f1amiento Profesional - Colegio Santo Domingo Savio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/#website\"},\"datePublished\":\"2021-05-05T11:15:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dfdb4afc92a954e307946b4c7b72b0f4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/jap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornadas de Acompa\u00f1amiento Profesional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Santo Domingo Savio\",\"description\":\"P\u00e1gina oficial Salesianos Monz\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/monzon.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dfdb4afc92a954e307946b4c7b72b0f4\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1e1fd8b2db3835fefe4cba3e9e0f57e2c8b7a51b7525c8a5e5f612d69fe34a31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1e1fd8b2db3835fefe4cba3e9e0f57e2c8b7a51b7525c8a5e5f612d69fe34a31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1e1fd8b2db3835fefe4cba3e9e0f57e2c8b7a51b7525c8a5e5f612d69fe34a31?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornadas de Acompa\u00f1amiento Profesional - Colegio Santo Domingo Savio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/","og_locale":"es_ES","og_type":"article","og_title":"Jornadas de Acompa\u00f1amiento Profesional - Colegio Santo Domingo Savio","og_description":"La Federaci\u00f3n de Antiguos Alumnos y Antiguas Alumnas de Don Bosco de nuestra zona ha desarrollado el proyecto JAP: Jornadas de Acompa\u00f1amiento Profesional.\u00a0 Por Rita Soriano Con el programa JAP la Asociaci\u00f3n de Antiguos Alumnos pretende cubrir uno de los objetivos: proteger y acompa\u00f1ar al alumnado. Han sido tres jornadas (en s\u00e1bado) en las que [&hellip;]","og_url":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/","og_site_name":"Colegio Santo Domingo Savio","article_published_time":"2021-05-05T11:15:45+00:00","author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/#article","isPartOf":{"@id":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/"},"author":{"name":"Gestor Web","@id":"https:\/\/monzon.salesianos.edu\/colegio\/#\/schema\/person\/dfdb4afc92a954e307946b4c7b72b0f4"},"headline":"Jornadas de Acompa\u00f1amiento Profesional","datePublished":"2021-05-05T11:15:45+00:00","mainEntityOfPage":{"@id":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/"},"wordCount":448,"commentCount":0,"articleSection":["Antiguos Alumnos","Bachillerato","Colegio","Familia Salesiana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/monzon.salesianos.edu\/colegio\/jap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/","url":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/","name":"Jornadas de Acompa\u00f1amiento Profesional - Colegio Santo Domingo Savio","isPartOf":{"@id":"https:\/\/monzon.salesianos.edu\/colegio\/#website"},"datePublished":"2021-05-05T11:15:45+00:00","author":{"@id":"https:\/\/monzon.salesianos.edu\/colegio\/#\/schema\/person\/dfdb4afc92a954e307946b4c7b72b0f4"},"breadcrumb":{"@id":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/monzon.salesianos.edu\/colegio\/jap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/monzon.salesianos.edu\/colegio\/jap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/monzon.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Jornadas de Acompa\u00f1amiento Profesional"}]},{"@type":"WebSite","@id":"https:\/\/monzon.salesianos.edu\/colegio\/#website","url":"https:\/\/monzon.salesianos.edu\/colegio\/","name":"Colegio Santo Domingo Savio","description":"P\u00e1gina oficial Salesianos Monz\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/monzon.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/monzon.salesianos.edu\/colegio\/#\/schema\/person\/dfdb4afc92a954e307946b4c7b72b0f4","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1e1fd8b2db3835fefe4cba3e9e0f57e2c8b7a51b7525c8a5e5f612d69fe34a31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1e1fd8b2db3835fefe4cba3e9e0f57e2c8b7a51b7525c8a5e5f612d69fe34a31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1e1fd8b2db3835fefe4cba3e9e0f57e2c8b7a51b7525c8a5e5f612d69fe34a31?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=10596"}],"version-history":[{"count":0,"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10596\/revisions"}],"wp:attachment":[{"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=10596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=10596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monzon.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=10596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}